{"id":1416,"count":3,"description":"<h2>Des poteaux de volley-ball de haute qualit\u00e9 pour votre entra\u00eenement et vos comp\u00e9titions<\/h2>\r\nNos <strong>poteaux de volley-ball<\/strong> se distinguent par leur robustesse et leur polyvalence. Que vous ayez besoin d'une installation professionnelle de volley-ball pour la comp\u00e9tition ou pour les loisirs, vous trouverez les produits adapt\u00e9s dans notre gamme.","link":"https:\/\/ruckstuhlsport.ch\/fr\/poteaux-de-volleyball\/","name":"Poteaux de volleyball","slug":"poteaux-de-volleyball","taxonomy":"product_cat","parent":1410,"meta":[],"cat_url":"https:\/\/ruckstuhlsport.ch\/fr\/poteaux-de-volleyball\/","_links":{"self":[{"href":"https:\/\/ruckstuhlsport.ch\/fr\/wp-json\/wp\/v2\/product_cat\/1416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ruckstuhlsport.ch\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ruckstuhlsport.ch\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ruckstuhlsport.ch\/fr\/wp-json\/wp\/v2\/product_cat\/1410"}],"wp:post_type":[{"href":"https:\/\/ruckstuhlsport.ch\/fr\/wp-json\/wp\/v2\/product?product_cat=1416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}